{"id":29998,"date":"2026-08-19T09:23:51","date_gmt":"2026-08-19T09:23:51","guid":{"rendered":"https:\/\/www.electroluxprofessional.com\/it\/?page_id=29998"},"modified":"2026-09-02T09:06:36","modified_gmt":"2026-09-02T09:06:36","slug":"centro-di-eccellenza-di-pordenone","status":"publish","type":"page","link":"https:\/\/www.electroluxprofessional.com\/it\/centro-di-eccellenza-di-pordenone\/","title":{"rendered":"Centro di Eccellenza di Pordenone"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;electroluxpro-container-large-no-padding&#8221; css=&#8221;.vc_custom_1787131549280{background-image: url(https:\/\/www.electroluxprofessional.com\/it\/wp-content\/uploads\/2026\/08\/CoE_2200x830-copy.webp?id=30000) !important;}&#8221;][vc_column][vc_empty_space height=&#8221;150px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-6&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<h1 style=\"color: #ffffff; font-size: 70px;\">Centri di<br \/>\nEccellenza<\/h1>\n<p>[\/vc_column_text][vc_empty_space][elx_heading font_size=&#8221;h5&#8243; text_color=&#8221;white&#8221;]Pordenone, Italia[\/elx_heading][vc_empty_space][elx_o2000_contact_us s=&#8221;Richiesta di dimostrazione di un prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; thanks=&#8221;Grazie! Vi contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; button_style=&#8221;primary-white-bordered&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-center-mobile&#8221; side_banner_title=&#8221;Prenota una demo presso il nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota una demo&#8221; r=&#8221;Vorrei essere contattato per organizzare una dimostrazione di prodotto presso il vostro Centro di Eccellenza di Pordenone.<br \/>\nSono interessato a&#8230; (per favore compilare)&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;100px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/5&#8243;][elx_heading text_color=&#8221;inherit&#8221;]Una rete globale di<br \/>\nispirazione e innovazione[\/elx_heading][vc_empty_space][vc_column_text css=&#8221;&#8221;]Il nostro <strong>Centro di Eccellenza<\/strong> \u00e8 un hub innovativo dove i professionisti possono esplorare tutto il potenziale delle nostre soluzioni. Progettato per ispirare, connettere e dare valore, offre dimostrazioni pratiche, consulenza di esperti, <strong>formazione<\/strong> <strong>personalizzata<\/strong> e <strong>approfondimenti <\/strong>preziosi per aiutare i clienti a plasmare il futuro della loro attivit\u00e0.[\/vc_column_text][vc_empty_space][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_single_image image=&#8221;29988&#8243; img_size=&#8221;full&#8221; css=&#8221;.vc_custom_1786449117825{border-radius: 20px !important;}&#8221;][\/vc_column][\/vc_row][vc_row el_id=&#8221;coe&#8221;][vc_column][vc_empty_space height=&#8221;50px&#8221;][elx_heading font_size=&#8221;h1&#8243; text_color=&#8221;electrolux-blue&#8221; text_align=&#8221;text-left&#8221;]Centro di Eccellenza di Pordenone [\/elx_heading][vc_column_text css=&#8221;&#8221;]<strong>Italia<\/strong>[\/vc_column_text][vc_empty_space height=&#8221;35px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]Scopri soluzioni professionali innovative nel nostro Centro di Eccellenza di Pordenone. Partecipa a dimostrazioni dal vivo, confrontati con i nostri esperti e vivi l&#8217;eccellenza in uno spazio pensato per ispirare.[\/vc_column_text][vc_row_inner][vc_column_inner][vc_empty_space height=&#8221;30px&#8221;][\/vc_column_inner][\/vc_row_inner][vc_column_text css=&#8221;&#8221;]<strong>Indirizzo<\/strong>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]<a href=\"https:\/\/maps.app.goo.gl\/w956S8QUhs2FX3yZA\" target=\"_blank\" rel=\"noopener\">Via Segaluzza, 30<br \/>\n33170 Pordenone (PN), Italia<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-30001\" src=\"https:\/\/www.electroluxprofessional.com\/it\/wp-content\/uploads\/2026\/08\/locator_icon.png\" alt=\"\" width=\"17\" height=\"23\" \/><\/a>[\/vc_column_text][vc_empty_space][vc_column_text css=&#8221;&#8221;]<strong>Orari di apertura<\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text css=&#8221;&#8221;]Lun &#8211; Ven<br \/>\n09:30 &#8211; 17:00<\/p>\n<p>Solo su appuntamento[\/vc_column_text][vc_empty_space height=&#8221;10px&#8221;][elx_o2000_contact_us s=&#8221;Richiesta di una dimostrazione del prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; thanks=&#8221;Grazie! Ti contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-left-mobile&#8221; side_banner_title=&#8221;Prenota una demo nel nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota una demo&#8221; r=&#8221;Vorrei essere contattato per organizzare una dimostrazione di prodotto presso il vostro Centro di Eccellenza a Pordenone.<br \/>\nSono interessato a&#8230; (per favore, completare)&#8221;][vc_empty_space height=&#8221;30px&#8221;][\/vc_column][vc_column width=&#8221;1\/2&#8243;][elx_promo_carousel_images promo_carousel=&#8221;%5B%7B%22text%22%3A%22Area%20bar%22%2C%22image%22%3A%2229994%22%7D%2C%7B%22text%22%3A%22Area%20cucina%22%2C%22image%22%3A%2229995%22%7D%2C%7B%22text%22%3A%22Area%20cucina%22%2C%22image%22%3A%2229996%22%7D%2C%7B%22text%22%3A%22Area%20lavanderia%22%2C%22image%22%3A%2229997%22%7D%5D&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;35px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;electroluxpro-container-large-no-padding&#8221;][vc_column][elx_heading text_color=&#8221;white&#8221; text_align=&#8221;text-center&#8221;]Cosa puoi vivere[\/elx_heading][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-row-light-blue&#8221;][vc_column][vc_empty_space height=&#8221;35px&#8221;][vc_row_inner][vc_column_inner offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_single_image image=&#8221;29989&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;&#8221;][vc_empty_space][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54890 size-full\" src=\"https:\/\/eprdev.comunicazione21.com\/wp-content\/uploads\/2025\/03\/icon_fork.png\" alt=\"\" width=\"80\" height=\"80\" \/><\/p>\n<h3>Ristorazione &amp; Beverage<\/h3>\n<style>a {<br \/>    text-decoration: none;<br \/>    color: #464feb;<br \/>}<br \/>tr th, tr td {<br \/>    border: 1px solid #e6e6e6;<br \/>}<br \/>tr th {<br \/>    background-color: #f5f5f5;<br \/>}<br \/><\/style>\n<div>\n<p><strong>Dimostrazioni di cucina dal vivo<\/strong> offrono opportunit\u00e0 uniche per scambiare esperienze, acquisire nuove idee e scoprire come le soluzioni Electrolux Professional possono rendere <strong>le operazioni nelle cucine professionali semplici e sicure<\/strong>, <strong>efficienti<\/strong> e, in ultima analisi, <strong>redditizie<\/strong>.<\/p>\n<p>Il nostro <strong>Centro di Eccellenza<\/strong> \u00e8 anche un hub globale per mostrare le ultime tendenze alimentari, favorire opportunit\u00e0 di networking e apprendimento, mettere in contatto <strong>culture culinarie<\/strong> e tradizioni diverse, e condividere idee innovative e tecniche avanzate.<\/div>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;25px&#8221;][elx_o2000_contact_us s=&#8221;Richiesta di una dimostrazione del prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; b=&#8221;food&#8221; thanks=&#8221;Grazie! Ti contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-center-mobile&#8221; side_banner_title=&#8221;Prenota una demo nel nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota una demo&#8221; r=&#8221;Vorrei essere contattato per organizzare una dimostrazione del prodotto presso il vostro Centro di Eccellenza a Pordenone.<br \/>\nSono interessato a&#8230; (si prega di completare)&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; offset=&#8221;vc_hidden-xs&#8221;][vc_single_image image=&#8221;29989&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;35px&#8221;][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-download-blue&#8221;][vc_column][vc_empty_space height=&#8221;35px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;29990&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-55368 size-medium\" src=\"https:\/\/eprdev.comunicazione21.com\/wp-content\/uploads\/2026\/08\/Langlebigkeit_icon_white-300x300-1.png\" alt=\"\" width=\"80\" height=\"80\" \/><\/span><\/p>\n<h3><span style=\"color: #ffffff;\">Lavanderia<\/span><\/h3>\n<p><span style=\"color: #ffffff;\">Entra in diversi ambienti lavanderia reali e scopri soluzioni su misura per varie esigenze aziendali. Esplora una lavanderia per l&#8217;ospitalit\u00e0 completamente attrezzata con lavatrici a carica frontale, asciugatrici e mangani, oltre a tecnologie avanzate di lavaggio a barriera progettate per strutture in cui l&#8217;igiene \u00e8 fondamentale, compresi i servizi sanitari e di emergenza.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Scopri <strong>lagoon\u00ae Advanced Care<\/strong>, il nostro innovativo sistema di lavaggio ad acqua, e apprendi come i detergenti dedicati contribuiscano a garantire un&#8217;eccellente cura dei capi con un approccio sostenibile.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Il Centro di Eccellenza presenta anche un&#8217;area dedicata <strong>myPRO<\/strong> che propone soluzioni professionali per lavanderie rivolte a piccole imprese e imprenditori.<\/span>[\/vc_column_text][vc_empty_space height=&#8221;25px&#8221;][elx_o2000_contact_us s=&#8221;Richiesta di dimostrazione di un prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; b=&#8221;laundry&#8221; thanks=&#8221;Grazie! Vi contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; button_style=&#8221;primary-white-bordered&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-center-mobile&#8221; side_banner_title=&#8221;Prenota una demo nel nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota una demo&#8221; r=&#8221;Vorrei essere contattato per organizzare una dimostrazione di prodotto presso il vostro Centro di Eccellenza a Pordenone.<br \/>\nSono interessato a&#8230; (si prega di completare)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;35px&#8221;][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-download-blue&#8221; disable_element=&#8221;yes&#8221;][vc_column][vc_empty_space height=&#8221;35px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;29990&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][vc_empty_space][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;&#8221;]<span style=\"color: #ffffff;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-55368 size-medium\" src=\"https:\/\/eprdev.comunicazione21.com\/wp-content\/uploads\/2026\/08\/Langlebigkeit_icon_white-300x300-1.png\" alt=\"\" width=\"80\" height=\"80\" \/><\/span><\/p>\n<h3><span style=\"color: #ffffff;\">Lavanderia<\/span><\/h3>\n<p><span style=\"color: #ffffff;\">Entra in diversi ambienti lavanderia reali e scopri soluzioni su misura per varie esigenze aziendali. Esplora una lavanderia per l&#8217;ospitalit\u00e0 completamente attrezzata con lavatrici a carica frontale, asciugatrici e mangani, oltre a tecnologie avanzate di lavaggio a barriera progettate per strutture in cui l&#8217;igiene \u00e8 fondamentale, compresi i servizi sanitari e di emergenza.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Scopri <strong>lagoon\u00ae Advanced Care<\/strong>, il nostro innovativo sistema di wet-cleaning, e apprendi come i detergenti dedicati contribuiscano a garantire un&#8217;eccellente cura dei capi con un approccio sostenibile.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Il Centro di Eccellenza presenta anche una moderna <strong>lavanderia multi-housing<\/strong>, con asciugatrici a pompa di calore, lavatrici e armadi asciuganti, insieme a un&#8217;area dedicata <strong>myPRO<\/strong> che propone soluzioni professionali per lavanderie rivolte a piccole imprese e imprenditori.<\/span>[\/vc_column_text][vc_empty_space height=&#8221;25px&#8221;][elx_o2000_contact_us s=&#8221;Richiesta di dimostrazione di un prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; b=&#8221;laundry&#8221; thanks=&#8221;Grazie! Vi contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; button_style=&#8221;primary-white-bordered&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-center-mobile&#8221; side_banner_title=&#8221;Prenota una demo nel nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota una demo&#8221; r=&#8221;Vorrei essere contattato per organizzare una dimostrazione di prodotto presso il vostro Centro di Eccellenza a Pordenone.<br \/>\nSono interessato a&#8230; (si prega di completare)&#8221;][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;35px&#8221;][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-row-light-blue&#8221;][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-row-light-blue&#8221; full_width=&#8221;electroluxpro-container-large&#8221;][vc_column width=&#8221;4\/12&#8243;][elx_heading text_color=&#8221;inherit&#8221;]Tour virtuale[\/elx_heading][vc_empty_space height=&#8221;20px&#8221;][vc_column_text css=&#8221;&#8221;]Vivi il nostro Centro di Eccellenza di Pordenone in 3D e scopri un polo di innovazione dove professionisti da tutto il mondo si connettono, imparano e trovano ispirazione.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][elx_button button_text=&#8221;Inizia il tour&#8221; button_style=&#8221;secondary-bordered&#8221; button_link=&#8221;url:https%3A%2F%2Fwww.electroluxprofessional.com%2Fit%2Fcentro-di-eccellenza-di-pordenone%2Fcenter-of-excellence-virtual-tour%2F&#8221;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][vc_empty_space][\/vc_column][vc_column width=&#8221;7\/12&#8243;][vc_single_image image=&#8221;29991&#8243; img_size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; css=&#8221;&#8221; link=&#8221;https:\/\/www.electroluxprofessional.com\/it\/it\/chefs-hub\/centers-of-excellence-virtual-tour\/&#8221;][\/vc_column][\/vc_row][vc_row custom_color_row=&#8221;bg-row-light-blue&#8221;][vc_column][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;electroluxpro-full-width&#8221;][vc_column][elx_heading text_color=&#8221;inherit&#8221; text_align=&#8221;text-center&#8221;]Potrebbe interessarti anche[\/elx_heading][vc_empty_space][\/vc_column][\/vc_row][vc_row full_width=&#8221;electroluxpro-full-width&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1785911884653{border-radius: 30px !important;}&#8221;][vc_single_image image=&#8221;29992&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][elx_heading font_container=&#8221;h3&#8243; text_color=&#8221;inherit&#8221; text_align=&#8221;text-left&#8221;]La nostra Chef Academy[\/elx_heading][vc_empty_space height=&#8221;20px&#8221;][vc_column_text css=&#8221;&#8221;]Scopri il nostro hub di ispirazione dove <strong>esperti mentori culinari<\/strong> e <strong>chef professionisti<\/strong> di tutto il mondo accolgono i nostri clienti.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][elx_button button_text=&#8221;Scopri di pi\u00f9&#8221; button_style=&#8221;secondary-bordered&#8221; button_link=&#8221;url:https%3A%2F%2Fwww.electroluxprofessional.com%2Fit%2Fcentro-di-eccellenza-di-pordenone%2Fchef-academy%2F|title:Scopri%20di%20pi%C3%B9&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm&#8221;][vc_empty_space][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;29993&#8243; img_size=&#8221;430&#215;280&#8243; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][elx_heading font_container=&#8221;h3&#8243; text_color=&#8221;inherit&#8221; text_align=&#8221;text-left&#8221;]Le nostre ricette[\/elx_heading][vc_empty_space height=&#8221;20px&#8221;][vc_column_text css=&#8221;&#8221;]Scopri ricette gustose e innovative ideate dalla Electrolux Professional Chef Academy per la tua cucina professionale.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221;][elx_button button_text=&#8221;Scopri di pi\u00f9&#8221; button_style=&#8221;secondary-bordered&#8221; button_link=&#8221;url:https%3A%2F%2Fwww.electroluxprofessional.com%2Fit%2Fcentro-di-eccellenza-di-pordenone%2Fricette%2F|title:Scopri%20di%20pi%C3%B9&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;60px&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;electroluxpro-container-large-no-padding&#8221; css=&#8221;.vc_custom_1787131549280{background-image: url(https:\/\/www.electroluxprofessional.com\/it\/wp-content\/uploads\/2026\/08\/CoE_2200x830-copy.webp?id=30000) !important;}&#8221;][vc_column][vc_empty_space height=&#8221;150px&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-4 vc_col-md-6&#8243;][vc_column_text css=&#8221;&#8221;] Centri di Eccellenza [\/vc_column_text][vc_empty_space][elx_heading font_size=&#8221;h5&#8243; text_color=&#8221;white&#8221;]Pordenone, Italia[\/elx_heading][vc_empty_space][elx_o2000_contact_us s=&#8221;Richiesta di dimostrazione di un prodotto presso il tuo Centro di Eccellenza&#8221; campaign=&#8221;701SX00000ktQdhYAE&#8221; text_send_button=&#8221;Prenota una demo&#8221; flag_hide_request_type=&#8221;true&#8221; country=&#8221;Italy&#8221; thanks=&#8221;Grazie! Vi contatteremo entro poche ore.&#8221; button_mode=&#8221;true&#8221; button_style=&#8221;primary-white-bordered&#8221; postion_button=&#8221;text-left&#8221; postion_button_mobile=&#8221;text-center-mobile&#8221; side_banner_title=&#8221;Prenota una demo presso il nostro Centro di Eccellenza&#8221; text_btn_contact=&#8221;Prenota [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29987,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-29998","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/pages\/29998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/comments?post=29998"}],"version-history":[{"count":15,"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/pages\/29998\/revisions"}],"predecessor-version":[{"id":30077,"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/pages\/29998\/revisions\/30077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/media\/29987"}],"wp:attachment":[{"href":"https:\/\/www.electroluxprofessional.com\/it\/wp-json\/wp\/v2\/media?parent=29998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}