{"id":12036,"date":"2020-08-20T14:51:30","date_gmt":"2020-08-20T14:51:30","guid":{"rendered":"https:\/\/www.electroluxprofessional.com\/fr\/?p=12036"},"modified":"2025-05-21T07:07:02","modified_gmt":"2025-05-21T07:07:02","slug":"ergonomie-cuisine-professionnelle","status":"publish","type":"post","link":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/","title":{"rendered":"L&rsquo;importance de l&rsquo;ergonomie en cuisine professionnelle"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]L\u2019ergonomie est un processus d\u2019adaptation de l\u2019environnement de travail aux besoins de l\u2019utilisateur. En tant que sujet d\u2019\u00e9tude scientifique, l\u2019ergonomie s\u2019int\u00e9resse aux conditions de travail et aux relations entre l\u2019\u00eatre humain et la machine. Appliqu\u00e9e dans la cuisine professionnelle, elle concerne la s\u00e9curit\u00e9 ainsi que l\u2019efficacit\u00e9. Par cons\u00e9quent, l\u2019ergonomie permet d\u2019augmenter la productivit\u00e9 en offrant une meilleure gestion du stress. L\u2019ergonomie en cuisine professionnelle\u00a0est donc un crit\u00e8re important \u00e0 prendre en consid\u00e9ration lors de l\u2019achat d\u2019\u00e9quipements ou la conception d\u2019une cuisine.<\/p>\n<h2>Un \u00e9quipement adapt\u00e9<\/h2>\n<p>Pour que votre cuisine r\u00e9ponde aux normes ergonomiques, le choix de son \u00e9quipement doit \u00eatre adapt\u00e9 au type de cuisine professionnelle concern\u00e9. Pour r\u00e9pondre aux besoins de production de 300 couverts dans un Ehpad, il ne faudra pas s\u2019appuyer sur le m\u00eame mat\u00e9riel que pour 300 couverts dans un h\u00f4pital ou une \u00e9cole. L\u2019installation devra \u00eatre fiable et performante, mais aussi ergonomique et conforme aux normes en vigueur. Et bien \u00e9videmment, adapt\u00e9e \u00e0 100 % \u00e0 votre activit\u00e9.<\/p>\n<p>Concernant le r\u00e9am\u00e9nagement ou la cr\u00e9ation d\u2019une cuisine, Electrolux Professional est le sp\u00e9cialiste des cuisines professionnelles r\u00e9pondant \u00e0 un cahier des charges ax\u00e9 sur l\u2019ergonomie.\u00a0 Qu\u2019il s\u2019agisse d\u2019\u00e9quiper <a href=\"https:\/\/www.ecoleducasse.com\/\">le centre de formation du Chef multi-\u00e9toil\u00e9 Alain Ducasse<\/a>, ou le snack d\u2019un nouveau jeune entrepreneur, l\u2019ergonomie est au c\u0153ur de nos pr\u00e9occupations.[\/vc_column_text][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb12037&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>Du mat\u00e9riel pr\u00e9vu pour de bonnes pratiques ergonomiques<\/h2>\n<p>L\u2019ergonomie en cuisine professionnelle permet de mettre \u00e0 disposition des brigades de cuisine, des \u00e9quipements qui leur faciliteront la t\u00e2che. Il est important que les bureaux d\u2019\u00e9tude tiennent comptent de l\u2019ergonomie pour proposer du mat\u00e9riel innovant mais aussi pratique pour les principaux concern\u00e9s\u00a0: les Chefs\u00a0!<\/p>\n<p>Electrolux Professional l\u2019a compris depuis longtemps et s\u2019appuie sur les recommandations des plus grands cuisiniers avant de concevoir du mat\u00e9riel, en coh\u00e9rence avec leurs attentes professionnelles et celles de leurs coll\u00e8gues.<\/p>\n<p>Voici quelques exemples d\u2019\u00e9quipements con\u00e7us avec un r\u00e9el souci de l\u2019ergonomie\u00a0:<\/p>\n<p><u>Lave-vaisselle<\/u>\u00a0:<\/p>\n<ul>\n<li>Avec capot \u00e0 ouverture automatique pour \u00e9viter des gestes inutiles et fatigants<\/li>\n<li>Nettoyage automatique des machines en fin de service<\/li>\n<li>Facilit\u00e9 d\u2019acc\u00e8s aux zones d\u2019entretien<\/li>\n<li>\u2026<\/li>\n<\/ul>\n<p><u>Armoire froide<\/u>\u00a0:<\/p>\n<ul>\n<li>Munie d\u2019une p\u00e9dale ou d\u2019un accessoire permettant d\u2019ouvrir les portes (car lorsqu\u2019un cuisinier tient dans ses mains une grosse casserole, l\u2019ouverture des armoires froides n\u2019est pas ais\u00e9e).<\/li>\n<\/ul>\n<p><u>Fours\u00a0et ustensiles : <\/u><\/p>\n<ul>\n<li>Ouverture facile des fours gr\u00e2ce \u00e0 des poign\u00e9es pouvant \u00eatre manipul\u00e9es avec le coude.<\/li>\n<li>Marmites basculantes pour faciliter leur vidange et leur nettoyage.<\/li>\n<li>\u2026.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb12038&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>L\u2019architecture des postes de travail<\/h2>\n<p>L\u2019\u00ab\u00a0architecture des postes\u00a0\u00bb \u00a0d\u00e9signe en ergonomie, l\u2019am\u00e9nagement des postes de travail. Une bonne configuration va directement impacter la performance et la bonne organisation d\u2019une cuisine professionnelle. Cela comprend\u00a0:<\/p>\n<ul>\n<li>Le choix de mat\u00e9riel adapt\u00e9 \u00e0 la production (voir ci-dessus)<\/li>\n<li>Un \u00e9quipement plac\u00e9 au bon endroit, par rapport au sens de la production<\/li>\n<li>Le confort de l\u2019utilisateur : il faut que tout (des assaisonnements au petit mat\u00e9riel) soit \u00e0 port\u00e9e de main.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_single_image image=\u00a0\u00bb12039&Prime; img_size=\u00a0\u00bbfull\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][vc_empty_space height=\u00a0\u00bb25px\u00a0\u00bb][vc_column_text]<\/p>\n<h2>Les efforts et postures sur les postes de travail<\/h2>\n<p>Bien \u00e9videmment, une bonne architecture des postes de travail permettra aux personnels de cuisine d\u2019\u00e9viter les efforts inutiles et les mauvaises postures. L\u2019objectif\u00a0? Faciliter le travail aux employ\u00e9s.<\/p>\n<p>L\u2019ergonomie en cuisine professionnelle impliquera notamment\u00a0:<\/p>\n<ul>\n<li>Une localisation optimale du mat\u00e9riel\u00a0: ustensiles et couteaux faciles \u00e0 attraper (aimants plac\u00e9s au-dessus des plans de travail, etc.\u2026)<\/li>\n<li>Une mise en place de plans de travail r\u00e9glables\u00a0en hauteur : pour les adapter aux besoins du personnel (taille, type de t\u00e2ches \u00e0 accomplir\u2026)<\/li>\n<\/ul>\n<h2>Pourquoi se soucier de l\u2019ergonomie ?<\/h2>\n<ul>\n<li>C\u2019est un gain de temps\u00a0: un des nombreux chefs qu\u2019Electrolux Professional consulte pour rester \u00e0 la pointe de l\u2019ergonomie en mati\u00e8re d\u2019\u00e9quipement de cuisine nous confiait que des \u00e9cueils et un manque de coh\u00e9rence dans ce domaine pouvaient entra\u00eener une perte 5 \u00e0 10% de son temps.<\/li>\n<li>Une bonne ergonomie r\u00e9duit le nombre d\u2019accidents du travail.<\/li>\n<li>On gagne \u00e9galement en \u00e9nergie pour le personnel, ce qui diminue aussi les potentiels arr\u00eats de travail (et donc les co\u00fbts d\u2019exploitation).<\/li>\n<li>Les brigades sont moins stress\u00e9es.<\/li>\n<li>Les r\u00e9glementations et obligations l\u00e9gales sont encore davantage respect\u00e9es.<\/li>\n<li>La productivit\u00e9 est am\u00e9lior\u00e9e.<\/li>\n<\/ul>\n<h2>L\u2019ergonomie en cuisine professionnelle oui, mais quand\u00a0?<\/h2>\n<p>L\u2019ergonomie sera utile <a href=\"https:\/\/www.electroluxprofessional.com\/fr\/conception-cuisine-professionnelle\/\">d\u00e8s la conception d\u2019une cuisine professionnelle<\/a> mais aussi lors de sa r\u00e9novation ou de son agrandissement.<\/p>\n<p>Elle permettra, lors d\u2019un audit, de trouver des solutions pour r\u00e9soudre les dysfonctionnements mis en \u00e9vidence. Il peut s\u2019agir de situations de travail rendues d\u00e9licates, de probl\u00e9matiques li\u00e9es \u00e0 la s\u00e9curit\u00e9 ou bien encore d\u2019organisation g\u00e9n\u00e9rale et de gestion des flux.<\/p>\n<p>Depuis plusieurs d\u00e9cennies, Electrolux Professional, conscient de l\u2019importance d\u2019int\u00e9grer l\u2019ergonomie dans son \u00e9quipement, fait appel \u00e0 des cuisiniers pour soutenir la r\u00e9flexion et l\u2019innovation de son bureau d\u2019\u00e9tudes.<\/p>\n<p><strong>Le r\u00e9sultat\u00a0: <\/strong><\/p>\n<ul>\n<li>Du mat\u00e9riel con\u00e7u pour \u00ab\u00a0coller\u00a0\u00bb aux v\u00e9ritables probl\u00e9matiques du m\u00e9tier<\/li>\n<li>Des plans de travail \u00e9tudi\u00e9s et fonctionnels<\/li>\n<li>Une am\u00e9lioration du fonctionnement des cuisines professionnelles<\/li>\n<\/ul>\n<p>Si vous \u00eates soucieux de l\u2019ergonomie en cuisine professionnelle, n\u2019h\u00e9sitez pas \u00e0 <a href=\"https:\/\/www.electroluxprofessional.com\/fr\/revendeurs-stc\/\">nous contacter<\/a> avant de vous lancer dans la conception ou la r\u00e9novation de votre outil de travail.[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>L\u2019ergonomie en cuisine professionnelle est un crit\u00e8re important \u00e0 prendre en consid\u00e9ration lors de l\u2019achat d\u2019\u00e9quipements ou la conception d\u2019une cuisine. D\u00e9couvrez pourquoi !<\/p>\n","protected":false},"author":4,"featured_media":12040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[97],"tags":[],"class_list":["post-12036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parole-dexperts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;importance de l&#039;ergonomie en cuisine professionnelle | Electrolux Professional France<\/title>\n<meta name=\"description\" content=\"L&#039;ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;importance de l&#039;ergonomie en cuisine professionnelle | Electrolux Professional France\" \/>\n<meta property=\"og:description\" content=\"L&#039;ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrolux Professional France\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-20T14:51:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T07:07:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emeline FOISSEY\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emeline FOISSEY\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/\"},\"author\":{\"name\":\"Emeline FOISSEY\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/#\\\/schema\\\/person\\\/906c23d4a5b968e56afa8a751bcd1893\"},\"headline\":\"L&rsquo;importance de l&rsquo;ergonomie en cuisine professionnelle\",\"datePublished\":\"2020-08-20T14:51:30+00:00\",\"dateModified\":\"2025-05-21T07:07:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/\"},\"wordCount\":1026,\"image\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ergonomie-cuisine-entete.jpg\",\"articleSection\":[\"Parole d'experts\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/\",\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/\",\"name\":\"L'importance de l'ergonomie en cuisine professionnelle | Electrolux Professional France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ergonomie-cuisine-entete.jpg\",\"datePublished\":\"2020-08-20T14:51:30+00:00\",\"dateModified\":\"2025-05-21T07:07:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/#\\\/schema\\\/person\\\/906c23d4a5b968e56afa8a751bcd1893\"},\"description\":\"L'ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ergonomie-cuisine-entete.jpg\",\"contentUrl\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/ergonomie-cuisine-entete.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"ergonomie-cuisine-entete\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/ergonomie-cuisine-professionnelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;importance de l&#8217;ergonomie en cuisine professionnelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/\",\"name\":\"Electrolux Professional France\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/?src={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/#\\\/schema\\\/person\\\/906c23d4a5b968e56afa8a751bcd1893\",\"name\":\"Emeline FOISSEY\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g\",\"caption\":\"Emeline FOISSEY\"},\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/fr\\\/author\\\/emeline\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'importance de l'ergonomie en cuisine professionnelle | Electrolux Professional France","description":"L'ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/","og_locale":"fr_FR","og_type":"article","og_title":"L'importance de l'ergonomie en cuisine professionnelle | Electrolux Professional France","og_description":"L'ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.","og_url":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/","og_site_name":"Electrolux Professional France","article_published_time":"2020-08-20T14:51:30+00:00","article_modified_time":"2025-05-21T07:07:02+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg","type":"image\/jpeg"}],"author":"Emeline FOISSEY","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Emeline FOISSEY","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#article","isPartOf":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/"},"author":{"name":"Emeline FOISSEY","@id":"https:\/\/www.electroluxprofessional.com\/fr\/#\/schema\/person\/906c23d4a5b968e56afa8a751bcd1893"},"headline":"L&rsquo;importance de l&rsquo;ergonomie en cuisine professionnelle","datePublished":"2020-08-20T14:51:30+00:00","dateModified":"2025-05-21T07:07:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/"},"wordCount":1026,"image":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg","articleSection":["Parole d'experts"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/","url":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/","name":"L'importance de l'ergonomie en cuisine professionnelle | Electrolux Professional France","isPartOf":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#primaryimage"},"image":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg","datePublished":"2020-08-20T14:51:30+00:00","dateModified":"2025-05-21T07:07:02+00:00","author":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/#\/schema\/person\/906c23d4a5b968e56afa8a751bcd1893"},"description":"L'ergonomie en cuisine professionnelle r\u00e9duit les accidents du travail, am\u00e9liore la productivit\u00e9 et respecte les r\u00e9glementations.","breadcrumb":{"@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#primaryimage","url":"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg","contentUrl":"https:\/\/www.electroluxprofessional.com\/fr\/wp-content\/uploads\/2020\/08\/ergonomie-cuisine-entete.jpg","width":2000,"height":1333,"caption":"ergonomie-cuisine-entete"},{"@type":"BreadcrumbList","@id":"https:\/\/www.electroluxprofessional.com\/fr\/ergonomie-cuisine-professionnelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.electroluxprofessional.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;importance de l&#8217;ergonomie en cuisine professionnelle"}]},{"@type":"WebSite","@id":"https:\/\/www.electroluxprofessional.com\/fr\/#website","url":"https:\/\/www.electroluxprofessional.com\/fr\/","name":"Electrolux Professional France","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.electroluxprofessional.com\/fr\/?src={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.electroluxprofessional.com\/fr\/#\/schema\/person\/906c23d4a5b968e56afa8a751bcd1893","name":"Emeline FOISSEY","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7fd4b5b42ae0382761d2472c48548c0b716b0dc9dcbcbe59a47fe4c80b17f981?s=96&d=mm&r=g","caption":"Emeline FOISSEY"},"url":"https:\/\/www.electroluxprofessional.com\/fr\/author\/emeline\/"}]}},"_links":{"self":[{"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/posts\/12036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/comments?post=12036"}],"version-history":[{"count":3,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/posts\/12036\/revisions"}],"predecessor-version":[{"id":19342,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/posts\/12036\/revisions\/19342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/media\/12040"}],"wp:attachment":[{"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/media?parent=12036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/categories?post=12036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.electroluxprofessional.com\/fr\/wp-json\/wp\/v2\/tags?post=12036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}