{"id":58,"count":78,"description":"","link":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/","name":"Sostenibilidad","slug":"sostenibilidad","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sostenibilidad Archives - Electrolux Professional Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostenibilidad Archives - Electrolux Professional Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Electrolux Professional Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/category\\\/sostenibilidad\\\/\",\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/category\\\/sostenibilidad\\\/\",\"name\":\"Sostenibilidad Archives - Electrolux Professional Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/#website\"},\"description\":\"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/category\\\/sostenibilidad\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/category\\\/sostenibilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sostenibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/\",\"name\":\"Electrolux Professional Espa\u00f1a\",\"description\":\"Equipamiento cocinas profesionales y lavander\u00edas comerciales. Excelencia en el suministro de soluciones profesionales.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.electroluxprofessional.com\\\/es\\\/?src={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sostenibilidad Archives - Electrolux Professional Espa\u00f1a","description":"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/","og_locale":"es_ES","og_type":"article","og_title":"Sostenibilidad Archives - Electrolux Professional Espa\u00f1a","og_description":"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.","og_url":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/","og_site_name":"Electrolux Professional Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/","url":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/","name":"Sostenibilidad Archives - Electrolux Professional Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.electroluxprofessional.com\/es\/#website"},"description":"Noticias de Electrolux Professional sobre sostenibilidad y tendencias en el sector de lavander\u00eda y restauraci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.electroluxprofessional.com\/es\/category\/sostenibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.electroluxprofessional.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sostenibilidad"}]},{"@type":"WebSite","@id":"https:\/\/www.electroluxprofessional.com\/es\/#website","url":"https:\/\/www.electroluxprofessional.com\/es\/","name":"Electrolux Professional Espa\u00f1a","description":"Equipamiento cocinas profesionales y lavander\u00edas comerciales. Excelencia en el suministro de soluciones profesionales.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.electroluxprofessional.com\/es\/?src={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.electroluxprofessional.com\/es\/wp-json\/wp\/v2\/categories\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.electroluxprofessional.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.electroluxprofessional.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.electroluxprofessional.com\/es\/wp-json\/wp\/v2\/posts?categories=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}